{"id":1456,"count":39,"description":"Kraze Mega X est une marque de saveurs intenses et rafra\u00eechissantes, pens\u00e9e pour ceux qui aiment les ar\u00f4mes audacieux et bien d\u00e9finis. Chaque profil est con\u00e7u pour offrir une exp\u00e9rience fruit\u00e9e ou fra\u00eeche marqu\u00e9e, avec une sensation nette et plaisante \u00e0 chaque utilisation","link":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/","name":"Kraze Mega x","slug":"kraze-mega-x","taxonomy":"marque","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kraze Mega x - Vape W\u00f4linak<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kraze Mega x - Vape W\u00f4linak\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/\" \/>\n<meta property=\"og:site_name\" content=\"Vape W\u00f4linak\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vapewolinak.com\/wp-content\/uploads\/2024\/04\/DSC_0014.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kraze Mega x - Vape W\u00f4linak","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/","og_locale":"en_US","og_type":"article","og_title":"Kraze Mega x - Vape W\u00f4linak","og_url":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/","og_site_name":"Vape W\u00f4linak","og_image":[{"width":1920,"height":1080,"url":"https:\/\/vapewolinak.com\/wp-content\/uploads\/2024\/04\/DSC_0014.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/","url":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/","name":"Kraze Mega x - Vape W\u00f4linak","isPartOf":{"@id":"https:\/\/vapewolinak.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/vapewolinak.com\/en\/marque\/kraze-mega-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vapewolinak.com\/en\/accueil\/"},{"@type":"ListItem","position":2,"name":"Kraze Mega x"}]},{"@type":"WebSite","@id":"https:\/\/vapewolinak.com\/en\/#website","url":"https:\/\/vapewolinak.com\/en\/","name":"Vape W\u00f4linak","description":"Articles et saveurs de vapotage au Qu\u00e9bec","publisher":{"@id":"https:\/\/vapewolinak.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vapewolinak.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vapewolinak.com\/en\/#organization","name":"Vape W\u00f4linak","url":"https:\/\/vapewolinak.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vapewolinak.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/vapewolinak.com\/wp-content\/uploads\/2024\/01\/vapewolinak-logo-e1736438957668.png","contentUrl":"https:\/\/vapewolinak.com\/wp-content\/uploads\/2024\/01\/vapewolinak-logo-e1736438957668.png","width":538,"height":440,"caption":"Vape W\u00f4linak"},"image":{"@id":"https:\/\/vapewolinak.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/vapewolinak.com\/en\/wp-json\/wp\/v2\/marque\/1456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vapewolinak.com\/en\/wp-json\/wp\/v2\/marque"}],"about":[{"href":"https:\/\/vapewolinak.com\/en\/wp-json\/wp\/v2\/taxonomies\/marque"}],"wp:post_type":[{"href":"https:\/\/vapewolinak.com\/en\/wp-json\/wp\/v2\/product?marque=1456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}